{"id":9332,"date":"2024-01-16T07:16:28","date_gmt":"2024-01-16T07:16:28","guid":{"rendered":"https:\/\/www.pyo1.go.th\/site\/?p=9332"},"modified":"2024-02-12T07:37:21","modified_gmt":"2024-02-12T07:37:21","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97","status":"publish","type":"post","link":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/","title":{"rendered":"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23"},"content":{"rendered":"<div dir=\"auto\">\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e55 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48<\/div>\n<div dir=\"auto\">\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e0a\u0e19\u0e18\u0e31\u0e0d \u0e15\u0e34\u0e4a\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e32,<\/div>\n<div dir=\"auto\">\u0e14\u0e23.\u0e10\u0e34\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c,\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e22\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\/\u0e2b\u0e19\u0e48\u0e27\u0e22<\/div>\n<div dir=\"auto\">\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/div>\n<div dir=\"auto\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23<\/div>\n<div dir=\"auto\">\u0e1e\u0e25.\u0e15.\u0e2d.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e2a\u0e1e\u0e10. \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a Zoom Meeting<\/div>\n<div dir=\"auto\">\u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 Video Conference<\/div>\n<div dir=\"auto\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9333\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419589541_886351659946638_2586968848922881090_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419589541_886351659946638_2586968848922881090_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419589541_886351659946638_2586968848922881090_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419589541_886351659946638_2586968848922881090_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419589541_886351659946638_2586968848922881090_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9334\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419598745_886351583279979_1815584578671611312_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419598745_886351583279979_1815584578671611312_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419598745_886351583279979_1815584578671611312_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419598745_886351583279979_1815584578671611312_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419598745_886351583279979_1815584578671611312_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9335\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419617841_886351566613314_5215959132798784471_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419617841_886351566613314_5215959132798784471_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419617841_886351566613314_5215959132798784471_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419617841_886351566613314_5215959132798784471_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/419617841_886351566613314_5215959132798784471_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9336\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420144262_886351469946657_5887002216754999285_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420144262_886351469946657_5887002216754999285_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420144262_886351469946657_5887002216754999285_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420144262_886351469946657_5887002216754999285_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420144262_886351469946657_5887002216754999285_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9337\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420148771_886351493279988_466940606668283330_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420148771_886351493279988_466940606668283330_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420148771_886351493279988_466940606668283330_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420148771_886351493279988_466940606668283330_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420148771_886351493279988_466940606668283330_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9338\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420149674_886351689946635_2284274219895760327_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420149674_886351689946635_2284274219895760327_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420149674_886351689946635_2284274219895760327_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420149674_886351689946635_2284274219895760327_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420149674_886351689946635_2284274219895760327_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9339\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420160443_886351749946629_7092516302336958752_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420160443_886351749946629_7092516302336958752_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420160443_886351749946629_7092516302336958752_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420160443_886351749946629_7092516302336958752_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420160443_886351749946629_7092516302336958752_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9340\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420175479_886351459946658_7500246615717906752_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420175479_886351459946658_7500246615717906752_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420175479_886351459946658_7500246615717906752_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420175479_886351459946658_7500246615717906752_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420175479_886351459946658_7500246615717906752_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9341\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420192011_886351419946662_7812656843436385933_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420192011_886351419946662_7812656843436385933_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420192011_886351419946662_7812656843436385933_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420192011_886351419946662_7812656843436385933_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420192011_886351419946662_7812656843436385933_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9342\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n-212x300.jpg 212w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n-724x1024.jpg 724w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n-768x1086.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n-1086x1536.jpg 1086w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194564_886352113279926_3770411762532637562_n.jpg 1448w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9343\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194869_886351786613292_173311233501951933_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194869_886351786613292_173311233501951933_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194869_886351786613292_173311233501951933_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194869_886351786613292_173311233501951933_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420194869_886351786613292_173311233501951933_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9344\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n-300x135.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n-1024x461.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n-768x346.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n-1536x692.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420197981_886351396613331_1847251571893358757_n.jpg 1906w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9345\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420213314_886351789946625_5720570846253651932_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420213314_886351789946625_5720570846253651932_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420213314_886351789946625_5720570846253651932_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420213314_886351789946625_5720570846253651932_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420213314_886351789946625_5720570846253651932_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9346\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420224624_886351856613285_7662942634911279432_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420224624_886351856613285_7662942634911279432_n-300x225.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420224624_886351856613285_7662942634911279432_n-1024x768.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420224624_886351856613285_7662942634911279432_n-768x576.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/420224624_886351856613285_7662942634911279432_n.jpg 1479w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9347\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15-300x168.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15-1024x572.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15-768x429.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15.jpg 1458w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e51\u0e55 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e57 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e0a\u0e19\u0e18\u0e31\u0e0d \u0e15\u0e34\u0e4a\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e32, \u0e14\u0e23.\u0e10\u0e34\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c,\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e22\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\/\u0e2b\u0e19\u0e48\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e1e\u0e25.\u0e15.\u0e2d.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25 \u0e0a\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e2a\u0e1e\u0e10. \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a Zoom Meeting \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 Video Conference \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/p>\n","protected":false},"author":2,"featured_media":9347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1<\/title>\n<meta name=\"description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23-\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23-\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PhayaoOne\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T07:16:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-12T07:37:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1458\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pr Phayao1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pr Phayao1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/\"},\"author\":{\"name\":\"pr Phayao1\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\"},\"headline\":\"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\",\"datePublished\":\"2024-01-16T07:16:28+00:00\",\"dateModified\":\"2024-02-12T07:37:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/\"},\"wordCount\":4,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"articleSection\":[\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/\",\"name\":\"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\"},\"datePublished\":\"2024-01-16T07:16:28+00:00\",\"dateModified\":\"2024-02-12T07:37:21+00:00\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"contentUrl\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"width\":1250,\"height\":1250,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\"},\"image\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PhayaoOne\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\",\"name\":\"pr Phayao1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"caption\":\"pr Phayao1\"},\"url\":\"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23-\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\/","og_locale":"en_US","og_type":"article","og_title":"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","og_description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","og_url":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23-\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","article_publisher":"https:\/\/www.facebook.com\/PhayaoOne","article_published_time":"2024-01-16T07:16:28+00:00","article_modified_time":"2024-02-12T07:37:21+00:00","og_image":[{"width":1458,"height":815,"url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/02\/\u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e19\u0e04\u0e34\u0e21\u0e0a\u0e38\u0e14\u0e19\u0e34\u0e2a\u0e34\u0e15.jpg","type":"image\/jpeg"}],"author":"pr Phayao1","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pr Phayao1","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/#article","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/"},"author":{"name":"pr Phayao1","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca"},"headline":"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23","datePublished":"2024-01-16T07:16:28+00:00","dateModified":"2024-02-12T07:37:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/"},"wordCount":4,"commentCount":0,"publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"articleSection":["\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/","url":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/","name":"\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/#website"},"datePublished":"2024-01-16T07:16:28+00:00","dateModified":"2024-02-12T07:37:21+00:00","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pyo1.go.th\/site\/2024\/01\/16\/%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9f%e0%b8%b1%e0%b8%87%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%a3%e0%b8%b2%e0%b8%8a%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%97\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pyo1.go.th\/site\/#website","url":"https:\/\/www.pyo1.go.th\/site\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"","publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pyo1.go.th\/site\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","url":"https:\/\/www.pyo1.go.th\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","contentUrl":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","width":1250,"height":1250,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1"},"image":{"@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PhayaoOne"]},{"@type":"Person","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca","name":"pr Phayao1","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","caption":"pr Phayao1"},"url":"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/comments?post=9332"}],"version-history":[{"count":1,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9332\/revisions"}],"predecessor-version":[{"id":9348,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9332\/revisions\/9348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media\/9347"}],"wp:attachment":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media?parent=9332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/categories?post=9332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/tags?post=9332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}