{"id":9112,"date":"2024-01-11T09:05:50","date_gmt":"2024-01-11T09:05:50","guid":{"rendered":"https:\/\/www.pyo1.go.th\/site\/?p=9112"},"modified":"2024-01-11T09:05:50","modified_gmt":"2024-01-11T09:05:50","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19"},"content":{"rendered":"<p class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e55 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e56\u0e57 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19<\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e14\u0e23.\u0e10\u0e34\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c <\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 <\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23<\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e20\u0e31\u0e17\u0e23\u0e20\u0e23 \u0e23\u0e31\u0e15\u0e19\u0e0a\u0e21\u0e20\u0e39 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e19\u0e32\u0e07\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e0e\u0e32 <\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a <\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e14\u0e2d\u0e22\u0e2b\u0e25\u0e27\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9113\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_12.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9114\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_14.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9115\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_19.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9116\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_21.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9117\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_28.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9118\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_29.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9119\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_32.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9120\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_34.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9121\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9122\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_41.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9123\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_51.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9124\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_55.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9125\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_57.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9126\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_60.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9127\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_63.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9128\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_64.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9129\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67-300x200.jpg 300w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67-1024x683.jpg 1024w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67-768x512.jpg 768w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67-1536x1024.jpg 1536w, https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_67.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e55 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 \u0e1e.\u0e28. \u0e52\u0e55\u0e56\u0e57 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49 \u0e14\u0e23.\u0e10\u0e34\u0e15\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e07\u0e20\u0e31\u0e17\u0e23\u0e20\u0e23 \u0e23\u0e31\u0e15\u0e19\u0e0a\u0e21\u0e20\u0e39 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e19\u0e32\u0e07\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e0e\u0e32 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e14\u0e2d\u0e22\u0e2b\u0e25\u0e27\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/p>\n","protected":false},"author":2,"featured_media":9121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1<\/title>\n<meta name=\"description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PhayaoOne\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-11T09:05:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pr Phayao1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pr Phayao1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/\"},\"author\":{\"name\":\"pr Phayao1\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\"},\"headline\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\",\"datePublished\":\"2024-01-11T09:05:50+00:00\",\"dateModified\":\"2024-01-11T09:05:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"articleSection\":[\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\"},\"datePublished\":\"2024-01-11T09:05:50+00:00\",\"dateModified\":\"2024-01-11T09:05:50+00:00\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"contentUrl\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"width\":1250,\"height\":1250,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\"},\"image\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PhayaoOne\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\",\"name\":\"pr Phayao1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"caption\":\"pr Phayao1\"},\"url\":\"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","og_description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","og_url":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","article_publisher":"https:\/\/www.facebook.com\/PhayaoOne","article_published_time":"2024-01-11T09:05:50+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/01\/LINE_ALBUM_2024.1.11_240111_36.jpg","type":"image\/jpeg"}],"author":"pr Phayao1","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pr Phayao1","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/#article","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/"},"author":{"name":"pr Phayao1","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca"},"headline":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19","datePublished":"2024-01-11T09:05:50+00:00","dateModified":"2024-01-11T09:05:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"articleSection":["\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/","url":"https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/","name":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e35\u0e49\u0e41\u0e08\u0e07\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e16\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/#website"},"datePublished":"2024-01-11T09:05:50+00:00","dateModified":"2024-01-11T09:05:50+00:00","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pyo1.go.th\/site\/2024\/01\/11\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%b5%e0%b9%89%e0%b9%81%e0%b8%88%e0%b8%87%e0%b8%84%e0%b8%b1%e0%b8%94%e0%b9%80%e0%b8%a5%e0%b8%b7%e0%b8%ad%e0%b8%81%e0%b9%82%e0%b8%a3\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pyo1.go.th\/site\/#website","url":"https:\/\/www.pyo1.go.th\/site\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"","publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pyo1.go.th\/site\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","url":"https:\/\/www.pyo1.go.th\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","contentUrl":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","width":1250,"height":1250,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1"},"image":{"@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PhayaoOne"]},{"@type":"Person","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca","name":"pr Phayao1","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","caption":"pr Phayao1"},"url":"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/comments?post=9112"}],"version-history":[{"count":1,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9112\/revisions"}],"predecessor-version":[{"id":9130,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/9112\/revisions\/9130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media\/9121"}],"wp:attachment":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media?parent=9112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/categories?post=9112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/tags?post=9112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}