{"id":30905,"date":"2026-03-20T09:11:35","date_gmt":"2026-03-20T09:11:35","guid":{"rendered":"https:\/\/www.pyo1.go.th\/site\/?p=30905"},"modified":"2026-03-20T09:11:35","modified_gmt":"2026-03-20T09:11:35","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5","status":"publish","type":"post","link":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e52\u0e50 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e59 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e22\u0e1b\u0e31\u0e0d\u0e0d\u0e32 , \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c , \u0e19\u0e32\u0e22\u0e27\u0e32\u0e17\u0e35 \u0e2a\u0e21\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e2f \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e14\u0e2d\u0e22\u0e2b\u0e25\u0e27\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30907\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/1-26.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30908\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/2-26.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30909\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/3-22.jpg\" alt=\"\" width=\"300\" height=\"230\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30910\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/4-16.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30911\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/5-12.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30912\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/6-9.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-30913\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/7-6.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e52\u0e50 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e52\u0e55\u0e56\u0e59 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e22\u0e1b\u0e31\u0e0d\u0e0d\u0e32 , \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c , \u0e19\u0e32\u0e22\u0e27\u0e32\u0e17\u0e35 \u0e2a\u0e21\u0e28\u0e23\u0e35 \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e2f \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e14\u0e2d\u0e22\u0e2b\u0e25\u0e27\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":30906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-30905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1<\/title>\n<meta name=\"description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23-5\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PhayaoOne\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T09:11:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/1-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pr Phayao1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pr Phayao1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/\"},\"author\":{\"name\":\"pr Phayao1\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\"},\"headline\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59\",\"datePublished\":\"2026-03-20T09:11:35+00:00\",\"dateModified\":\"2026-03-20T09:11:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/\"},\"wordCount\":2,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"articleSection\":[\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\"},\"datePublished\":\"2026-03-20T09:11:35+00:00\",\"dateModified\":\"2026-03-20T09:11:35+00:00\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"contentUrl\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"width\":1250,\"height\":1250,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\"},\"image\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PhayaoOne\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\",\"name\":\"pr Phayao1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"caption\":\"pr Phayao1\"},\"url\":\"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23-5\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","og_description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","og_url":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23-5\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","article_publisher":"https:\/\/www.facebook.com\/PhayaoOne","article_published_time":"2026-03-20T09:11:35+00:00","og_image":[{"url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/03\/1-25.jpg","width":750,"height":500,"type":"image\/jpeg"}],"author":"pr Phayao1","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pr Phayao1","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/#article","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/"},"author":{"name":"pr Phayao1","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca"},"headline":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59","datePublished":"2026-03-20T09:11:35+00:00","dateModified":"2026-03-20T09:11:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/"},"wordCount":2,"commentCount":0,"publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"articleSection":["\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/","url":"https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/","name":"\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 \u0e51\/\u0e52\u0e55\u0e56\u0e59 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/#website"},"datePublished":"2026-03-20T09:11:35+00:00","dateModified":"2026-03-20T09:11:35+00:00","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pyo1.go.th\/site\/2026\/03\/20\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3-5\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pyo1.go.th\/site\/#website","url":"https:\/\/www.pyo1.go.th\/site\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"","publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pyo1.go.th\/site\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","url":"https:\/\/www.pyo1.go.th\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","contentUrl":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","width":1250,"height":1250,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1"},"image":{"@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PhayaoOne"]},{"@type":"Person","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca","name":"pr Phayao1","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","caption":"pr Phayao1"},"url":"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/30905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/comments?post=30905"}],"version-history":[{"count":1,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/30905\/revisions"}],"predecessor-version":[{"id":30914,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/30905\/revisions\/30914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media\/30906"}],"wp:attachment":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media?parent=30905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/categories?post=30905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/tags?post=30905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}