{"id":29704,"date":"2026-02-02T03:25:45","date_gmt":"2026-02-02T03:25:45","guid":{"rendered":"https:\/\/www.pyo1.go.th\/site\/?p=29704"},"modified":"2026-02-02T03:25:45","modified_gmt":"2026-02-02T03:25:45","slug":"%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83","status":"publish","type":"post","link":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/","title":{"rendered":"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e52 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e4c \u0e52\u0e55\u0e56\u0e59 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 , \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e38\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e32 \u0e2d\u0e21\u0e34\u0e15\u0e40\u0e14\u0e0a\u0e42\u0e0a\u0e15\u0e34 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29706\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/47F4D154-0586-4495-8539-743933633738.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29707\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/668AF9EB-3C6F-4A69-AF75-DB5968B5ED79.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29708\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/2773C6A2-CE3E-4751-BE9D-D2748F28F47D.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29709\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/C50896BB-E8A4-4A9F-BCF9-EDF1C1F93668.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29710\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/E1737757-BD8B-4DD1-8955-439AF7D2863B-1.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29711\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/F60FE3EE-1FAC-486B-9451-925445BC8C41.jpg\" alt=\"\" width=\"300\" height=\"169\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-29712\" src=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/F0892730-23E0-487B-A1F5-0BA6BB474E96.jpg\" alt=\"\" width=\"300\" height=\"169\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e35\u0e48 \u0e52 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e4c \u0e52\u0e55\u0e56\u0e59 \u0e14\u0e23.\u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e04\u0e33\u0e1b\u0e27\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e19\u0e32\u0e22\u0e2a\u0e38\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 , \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e23\u0e38\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e41\u0e01\u0e49\u0e27\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e32 \u0e2d\u0e21\u0e34\u0e15\u0e40\u0e14\u0e0a\u0e42\u0e0a\u0e15\u0e34 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 \u0e51 &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":29705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pgc_sgb_lightbox_settings":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-29704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1<\/title>\n<meta name=\"description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PhayaoOne\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T03:25:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/E1737757-BD8B-4DD1-8955-439AF7D2863B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pr Phayao1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"pr Phayao1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/\"},\"author\":{\"name\":\"pr Phayao1\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\"},\"headline\":\"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21\",\"datePublished\":\"2026-02-02T03:25:45+00:00\",\"dateModified\":\"2026-02-02T03:25:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"articleSection\":[\"\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/\",\"name\":\"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"isPartOf\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\"},\"datePublished\":\"2026-02-02T03:25:45+00:00\",\"dateModified\":\"2026-02-02T03:25:45+00:00\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#website\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"contentUrl\":\"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png\",\"width\":1250,\"height\":1250,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1\"},\"image\":{\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PhayaoOne\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca\",\"name\":\"pr Phayao1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g\",\"caption\":\"pr Phayao1\"},\"url\":\"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\/","og_locale":"en_US","og_type":"article","og_title":"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","og_description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","og_url":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","article_publisher":"https:\/\/www.facebook.com\/PhayaoOne","article_published_time":"2026-02-02T03:25:45+00:00","og_image":[{"url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2026\/02\/E1737757-BD8B-4DD1-8955-439AF7D2863B.jpg","width":750,"height":422,"type":"image\/jpeg"}],"author":"pr Phayao1","twitter_card":"summary_large_image","twitter_misc":{"Written by":"pr Phayao1","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/#article","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/"},"author":{"name":"pr Phayao1","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca"},"headline":"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21","datePublished":"2026-02-02T03:25:45+00:00","dateModified":"2026-02-02T03:25:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"articleSection":["\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/","url":"https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/","name":"\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e08\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 O-NET \u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e52\u0e55\u0e56\u0e58 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 \u0e53 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Digital Testing \u0e13 \u0e2a\u0e19\u0e32\u0e21\u0e2a\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e4b\u0e2d\u0e21 - \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","isPartOf":{"@id":"https:\/\/www.pyo1.go.th\/site\/#website"},"datePublished":"2026-02-02T03:25:45+00:00","dateModified":"2026-02-02T03:25:45+00:00","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e2a\u0e1e\u0e1b.\u0e1e\u0e30\u0e40\u0e22\u0e32.1,\u0e1e\u0e30\u0e40\u0e22\u0e32 1,\u0e40\u0e02\u0e15 1, \u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1, \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, \u0e2a\u0e1e\u0e10.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pyo1.go.th\/site\/2026\/02\/02\/%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b9%80%e0%b8%a2%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a1%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%83%e0%b8%ab%e0%b9%89%e0%b8%81%e0%b8%b3%e0%b8%a5%e0%b8%b1%e0%b8%87%e0%b9%83\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pyo1.go.th\/site\/#website","url":"https:\/\/www.pyo1.go.th\/site\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","description":"","publisher":{"@id":"https:\/\/www.pyo1.go.th\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pyo1.go.th\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pyo1.go.th\/site\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1","url":"https:\/\/www.pyo1.go.th\/site\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","contentUrl":"https:\/\/www.pyo1.go.th\/site\/wp-content\/uploads\/2024\/05\/Logo20240514.png","width":1250,"height":1250,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e30\u0e40\u0e22\u0e32 \u0e40\u0e02\u0e15 1"},"image":{"@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PhayaoOne"]},{"@type":"Person","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/7b0b23f7dde58a2114aa4944b1614eca","name":"pr Phayao1","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pyo1.go.th\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d55be3e1ddebe8c9da27d51f420210ed4587de3b6586aa1c723ee5da37ee997a?s=96&d=mm&r=g","caption":"pr Phayao1"},"url":"https:\/\/www.pyo1.go.th\/site\/author\/prphayao1\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/29704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/comments?post=29704"}],"version-history":[{"count":1,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/29704\/revisions"}],"predecessor-version":[{"id":29713,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/posts\/29704\/revisions\/29713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media\/29705"}],"wp:attachment":[{"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/media?parent=29704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/categories?post=29704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pyo1.go.th\/site\/wp-json\/wp\/v2\/tags?post=29704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}